{"id":193,"count":6,"description":"Mises en lum de formaires, partenaris o collaborators.","link":"https:\/\/cfpo.kiss-os.com\/oc-fr\/category\/retraches\/","name":"Retraches","slug":"retraches","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Archives des Retraches - CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cfpo.kiss-os.com\/oc-fr\/category\/retraches\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Retraches - CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane\" \/>\n<meta property=\"og:description\" content=\"Mises en lum de formaires, partenaris o collaborators.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cfpo.kiss-os.com\/oc-fr\/category\/retraches\/\" \/>\n<meta property=\"og:site_name\" content=\"CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/category\/retraches\/\",\"url\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/category\/retraches\/\",\"name\":\"Archives des Retraches - CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane\",\"isPartOf\":{\"@id\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/category\/retraches\/#breadcrumb\"},\"inLanguage\":\"oc-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/category\/retraches\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retraches\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/#website\",\"url\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/\",\"name\":\"CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane\",\"description\":\"Transmettre la langue et la culture occitanes, pour faire vivre nos territoires.\",\"publisher\":{\"@id\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"oc-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/#organization\",\"name\":\"CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane\",\"url\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"oc-FR\",\"@id\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cfpo.kiss-os.com\/wp-content\/uploads\/2025\/07\/logo_CFPO-Montanhol_L150.png\",\"contentUrl\":\"https:\/\/cfpo.kiss-os.com\/wp-content\/uploads\/2025\/07\/logo_CFPO-Montanhol_L150.png\",\"width\":278,\"height\":150,\"caption\":\"CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane\"},\"image\":{\"@id\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des Retraches - CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cfpo.kiss-os.com\/oc-fr\/category\/retraches\/","og_locale":"en_US","og_type":"article","og_title":"Archives des Retraches - CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane","og_description":"Mises en lum de formaires, partenaris o collaborators.","og_url":"https:\/\/cfpo.kiss-os.com\/oc-fr\/category\/retraches\/","og_site_name":"CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/cfpo.kiss-os.com\/oc-fr\/category\/retraches\/","url":"https:\/\/cfpo.kiss-os.com\/oc-fr\/category\/retraches\/","name":"Archives des Retraches - CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane","isPartOf":{"@id":"https:\/\/cfpo.kiss-os.com\/oc-fr\/#website"},"breadcrumb":{"@id":"https:\/\/cfpo.kiss-os.com\/oc-fr\/category\/retraches\/#breadcrumb"},"inLanguage":"oc-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/cfpo.kiss-os.com\/oc-fr\/category\/retraches\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/cfpo.kiss-os.com\/oc-fr\/"},{"@type":"ListItem","position":2,"name":"Retraches"}]},{"@type":"WebSite","@id":"https:\/\/cfpo.kiss-os.com\/oc-fr\/#website","url":"https:\/\/cfpo.kiss-os.com\/oc-fr\/","name":"CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane","description":"Transmettre la langue et la culture occitanes, pour faire vivre nos territoires.","publisher":{"@id":"https:\/\/cfpo.kiss-os.com\/oc-fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cfpo.kiss-os.com\/oc-fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"oc-FR"},{"@type":"Organization","@id":"https:\/\/cfpo.kiss-os.com\/oc-fr\/#organization","name":"CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane","url":"https:\/\/cfpo.kiss-os.com\/oc-fr\/","logo":{"@type":"ImageObject","inLanguage":"oc-FR","@id":"https:\/\/cfpo.kiss-os.com\/oc-fr\/#\/schema\/logo\/image\/","url":"https:\/\/cfpo.kiss-os.com\/wp-content\/uploads\/2025\/07\/logo_CFPO-Montanhol_L150.png","contentUrl":"https:\/\/cfpo.kiss-os.com\/wp-content\/uploads\/2025\/07\/logo_CFPO-Montanhol_L150.png","width":278,"height":150,"caption":"CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane"},"image":{"@id":"https:\/\/cfpo.kiss-os.com\/oc-fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cfpo.kiss-os.com\/oc-fr\/wp-json\/wp\/v2\/categories\/193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cfpo.kiss-os.com\/oc-fr\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/cfpo.kiss-os.com\/oc-fr\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/cfpo.kiss-os.com\/oc-fr\/wp-json\/wp\/v2\/posts?categories=193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}