{"id":120,"count":6,"description":"Dial\u00e8cte central, plan espandit, parlat entre Tolosa, Carcassona e Montpelhi\u00e8r.\t","link":"https:\/\/cfpo.kiss-os.com\/oc-fr\/parlar\/lengadocian\/","name":"Lengadocian","slug":"lengadocian","taxonomy":"parler","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lengadocian Archives - CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane<\/title>\n<meta name=\"description\" content=\"Dialecte le plus diffus\u00e9, le languedocien est souvent utilis\u00e9 comme standard dans l\u2019enseignement de l\u2019occitan.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cfpo.kiss-os.com\/oc-fr\/parlar\/lengadocian\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lengadocian Archives - CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane\" \/>\n<meta property=\"og:description\" content=\"Dialecte le plus diffus\u00e9, le languedocien est souvent utilis\u00e9 comme standard dans l\u2019enseignement de l\u2019occitan.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cfpo.kiss-os.com\/oc-fr\/parlar\/lengadocian\/\" \/>\n<meta property=\"og:site_name\" content=\"CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/parlar\/lengadocian\/\",\"url\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/parlar\/lengadocian\/\",\"name\":\"Lengadocian Archives - CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane\",\"isPartOf\":{\"@id\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/#website\"},\"description\":\"Dialecte le plus diffus\u00e9, le languedocien est souvent utilis\u00e9 comme standard dans l\u2019enseignement de l\u2019occitan.\",\"breadcrumb\":{\"@id\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/parlar\/lengadocian\/#breadcrumb\"},\"inLanguage\":\"oc-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/parlar\/lengadocian\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lengadocian\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/#website\",\"url\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/\",\"name\":\"CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane\",\"description\":\"Transmettre la langue et la culture occitanes, pour faire vivre nos territoires.\",\"publisher\":{\"@id\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"oc-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/#organization\",\"name\":\"CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane\",\"url\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"oc-FR\",\"@id\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cfpo.kiss-os.com\/wp-content\/uploads\/2025\/07\/logo_CFPO-Montanhol_L150.png\",\"contentUrl\":\"https:\/\/cfpo.kiss-os.com\/wp-content\/uploads\/2025\/07\/logo_CFPO-Montanhol_L150.png\",\"width\":278,\"height\":150,\"caption\":\"CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane\"},\"image\":{\"@id\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lengadocian Archives - CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane","description":"Dialecte le plus diffus\u00e9, le languedocien est souvent utilis\u00e9 comme standard dans l\u2019enseignement de l\u2019occitan.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cfpo.kiss-os.com\/oc-fr\/parlar\/lengadocian\/","og_locale":"en_US","og_type":"article","og_title":"Lengadocian Archives - CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane","og_description":"Dialecte le plus diffus\u00e9, le languedocien est souvent utilis\u00e9 comme standard dans l\u2019enseignement de l\u2019occitan.","og_url":"https:\/\/cfpo.kiss-os.com\/oc-fr\/parlar\/lengadocian\/","og_site_name":"CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/cfpo.kiss-os.com\/oc-fr\/parlar\/lengadocian\/","url":"https:\/\/cfpo.kiss-os.com\/oc-fr\/parlar\/lengadocian\/","name":"Lengadocian Archives - CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane","isPartOf":{"@id":"https:\/\/cfpo.kiss-os.com\/oc-fr\/#website"},"description":"Dialecte le plus diffus\u00e9, le languedocien est souvent utilis\u00e9 comme standard dans l\u2019enseignement de l\u2019occitan.","breadcrumb":{"@id":"https:\/\/cfpo.kiss-os.com\/oc-fr\/parlar\/lengadocian\/#breadcrumb"},"inLanguage":"oc-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/cfpo.kiss-os.com\/oc-fr\/parlar\/lengadocian\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/cfpo.kiss-os.com\/oc-fr\/"},{"@type":"ListItem","position":2,"name":"Lengadocian"}]},{"@type":"WebSite","@id":"https:\/\/cfpo.kiss-os.com\/oc-fr\/#website","url":"https:\/\/cfpo.kiss-os.com\/oc-fr\/","name":"CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane","description":"Transmettre la langue et la culture occitanes, pour faire vivre nos territoires.","publisher":{"@id":"https:\/\/cfpo.kiss-os.com\/oc-fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cfpo.kiss-os.com\/oc-fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"oc-FR"},{"@type":"Organization","@id":"https:\/\/cfpo.kiss-os.com\/oc-fr\/#organization","name":"CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane","url":"https:\/\/cfpo.kiss-os.com\/oc-fr\/","logo":{"@type":"ImageObject","inLanguage":"oc-FR","@id":"https:\/\/cfpo.kiss-os.com\/oc-fr\/#\/schema\/logo\/image\/","url":"https:\/\/cfpo.kiss-os.com\/wp-content\/uploads\/2025\/07\/logo_CFPO-Montanhol_L150.png","contentUrl":"https:\/\/cfpo.kiss-os.com\/wp-content\/uploads\/2025\/07\/logo_CFPO-Montanhol_L150.png","width":278,"height":150,"caption":"CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane"},"image":{"@id":"https:\/\/cfpo.kiss-os.com\/oc-fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cfpo.kiss-os.com\/oc-fr\/wp-json\/wp\/v2\/parler\/120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cfpo.kiss-os.com\/oc-fr\/wp-json\/wp\/v2\/parler"}],"about":[{"href":"https:\/\/cfpo.kiss-os.com\/oc-fr\/wp-json\/wp\/v2\/taxonomies\/parler"}],"wp:post_type":[{"href":"https:\/\/cfpo.kiss-os.com\/oc-fr\/wp-json\/wp\/v2\/formation?parler=120"},{"href":"https:\/\/cfpo.kiss-os.com\/oc-fr\/wp-json\/wp\/v2\/formateur?parler=120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}