{"id":5609,"date":"2024-05-02T00:00:00","date_gmt":"2024-05-01T22:00:00","guid":{"rendered":"https:\/\/cfpo.kiss-os.com\/non-categorise\/los-rescontres-occitanes-dauvergne-2024\/"},"modified":"2024-05-02T00:00:00","modified_gmt":"2024-05-01T22:00:00","slug":"los-rescontres-occitanes-dauvergne-2024","status":"publish","type":"post","link":"https:\/\/cfpo.kiss-os.com\/oc-fr\/eveniments\/los-rescontres-occitanes-dauvergne-2024\/","title":{"rendered":"los Rescontres occitanes d\u2019Auvergne 2024"},"content":{"rendered":"<div class=\"udesign-post-content\">\n<p>Las Rescontradas occitanas d\u2019Auv\u00e8rnhe 2024<\/p>\n<p>Lo CFPO Montanh\u00f2l vos convida a las Rescontradas occitanas d\u2019Auv\u00e8rnhe, del 6 al 10 de julhet de 2024 a Sant-Bonet-pr\u00e8s-Riom. Ven\u00e8tz viure una setmana d\u2019immersion dins la lenga, amb de corses de lenga sus los dial\u00e8ctes occitans, de partatges d\u2019experi\u00e9ncias, de confer\u00e9ncias, de talhi\u00e8rs practics, atal coma de conc\u00e8rts, bals e espectacles per enriquir v\u00f2stra experi\u00e9ncia culturala.<\/p>\n<p>\u2727 \u2729 \u272a \u272b \u272c \u272d \u272e \u272f \u2730 Estagis de lenga \u2727 \u2729 \u272a \u272b \u272c \u272d \u272e \u272f \u2730<\/p>\n<p>Amb \u00c9tienne ROUGIER, Laurent BOITHIAS, L\u00e9o BROSSY, Quentin GARNIER e Didier GRANGE<\/p>\n<p>Cada jorn, auretz l\u2019escasen\u00e7a d\u2019explorar los dial\u00e8ctes occitans a trav\u00e8rs cinc talhi\u00e8rs de lenga (Vivaro-Alpin, Auvernhat N\u00f2rd e Sud, Lengadocian e Interdialectal) animats per de formators exp\u00e8rts. Aqueles estagis ofrisson una immersion compl\u00e8ta, cobrissent la conjugason, la grammatica e lo vocabulari especific a cada dial\u00e8cte. Que siatz comen\u00e7airitz o confirmats, n\u00f2stres talhi\u00e8rs son concebuts per aprofundir v\u00f2stras compet\u00e9ncias ling\u00fcisticas e vos plonjar dins la cultura occitana.<\/p>\n<p>\u2727 \u2729 \u272a \u272b \u272c \u272d \u272e \u272f \u2730 Partatges d\u2019experi\u00e9ncias \u2727 \u2729 \u272a \u272b \u272c \u272d \u272e \u272f \u2730<\/p>\n<p>Amb Floren\u00e7 PONS, Yves DURAND, Nicolas PUECH, Jean ROUX, Bernard GIACOMO e Natacha MURACCIOLE<\/p>\n<p>Al c\u00f2r de las Rescontradas occitanas, los partatges d\u2019experi\u00e9ncias ofrir\u00e0n als participants l\u2019oportunitat de dialogar amb de realizaires, d\u2019artistas, d\u2019escrivans e d\u2019autras personalitats influentas de la cultura occitana. N\u00f2stres talhi\u00e8rs, cobrissent una varietat de domenis artistics e professionals, prometon una experi\u00e9ncia sus mesura. N\u00f2stre objectiu principal es de favorir d\u2019escambis autentics, encoratjant un dial\u00f2g dob\u00e8rt e dinamic entre los participants e los intervenents, dins lo but de prom\u00f2ure la compreneson mutuala e l\u2019inspiracion reciproca.<\/p>\n<p>\u2727 \u2729 \u272a \u272b \u272c \u272d \u272e \u272f \u2730 Confer\u00e9ncias \u2727 \u2729 \u272a \u272b \u272c \u272d \u272e \u272f \u2730<\/p>\n<p>Amb Catherine LEITHOUDT, Jean ROUX, Cristian OMELHIER e Philippe MARMY<\/p>\n<p>N\u00f2stras confer\u00e9ncias cobrisson un ample esp\u00e8ctre de subj\u00e8ctes ligats a la cultura, a l\u2019ist\u00f2ria e a la lenga occitanas, e ofrisson una plongada prigonda dins cada asp\u00e8cte. L\u2019objectiu es de crear un espaci interactiu ont n\u00f2stres estagiaris p\u00f2scan escotar de presentacions inspirantas, interagir amb los conferenci\u00e8rs e pausar de questions, en favorizant atal una compreneson mai prigonda e de discussions enriquissentas amb d\u2019exp\u00e8rts reconeguts.<\/p>\n<p>\u2727 \u2729 \u272a \u272b \u272c \u272d \u272e \u272f \u2730 Conc\u00e8rts, bals, espectacles \u2727 \u2729 \u272a \u272b \u272c \u272d \u272e \u272f \u2730<\/p>\n<p>Amb en particular la participacion de Cl\u00e9ment GIBERT, Didier HUGUET, Jean-Pierre LACOMBE e Josy GUILLOT<\/p>\n<p>Aquesta annada, las Rescontradas occitanas s\u2019associan al festenal Los Volcanics per una experi\u00e9ncia culturala immersiva. En mai dels contaires e musicians ja citats, n\u00f2stres estagiaris aur\u00e0n l\u2019escasen\u00e7a de participar als conc\u00e8rts, bals e espectacles prepausats pels Volcanics, \u00e7\u00f2 que donar\u00e0 una t\u00f2ca vibranta a lor estada.<\/p>\n<p>\u2727 \u2729 \u272a \u272b \u272c \u272d lo programa de las Rescontradas occitanas d\u2019Auv\u00e8rnhe 2024 \u2727 \u2729 \u272a \u272b \u272c \u272d<\/p>\n<p><img decoding=\"async\" src=\"\/UP\/3\/8fec7-capture-decran-2024-05-02-150326-1.png\" alt=\"Las Rescontradas occitanas d\u2019Auv\u00e8rnhe 2024\"><\/p>\n<p><img decoding=\"async\" src=\"\/UP\/3\/30dd9-capture-decran-2024-04-30-161958.png\" alt=\"Las Rescontradas occitanas d\u2019Auv\u00e8rnhe 2024\"><\/p>\n<p><img decoding=\"async\" src=\"\/UP\/3\/copie-de-rencontresoccitanes-tence-juillet22.png\" alt=\"Las Rescontradas occitanas d\u2019Auv\u00e8rnhe 2024\"><\/p>\n<p><img decoding=\"async\" src=\"\/UP\/3\/df8d5-capture-decran-2024-04-30-163043-1.png\" alt=\"Las Rescontradas occitanas d\u2019Auv\u00e8rnhe 2024\"><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>los Rescontres occitanes d\u2019Auvergne 2024 los Rescontres occitanes d\u2019Auvergne 2024 lo CFPO Montanh\u00f2l vous convie aux Rescontres occitanes d\u2019Auvergne, del 6 al 10 juillet 2024 a Saint-Bonnet-pr\u00e8s-Riom. Venez vivre une semaine d\u2019immersion dans la lenga , amb dels cours de.<\/p>\n","protected":false},"author":1,"featured_media":5435,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[180,183],"tags":[203,208,214],"class_list":["post-5609","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eveniments","category-rescontres-occitanas","tag-eveniment","tag-occitan-oc-fr","tag-rescontres-occitanas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>los Rescontres occitanes d\u2019Auvergne 2024<\/title>\n<meta name=\"description\" content=\"los Rescontres occitanes d\u2019Auvergne 2024 lo CFPO Montanh\u00f2l vous convie aux Rescontres occitanes d\u2019Auvergne, del 6 al 10 juillet 2024 a Saint-Bonnet-pr\u00e8s-Riom. Venez vivre\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cfpo-montanhol.org\/2024\/05\/02\/les-rencontres-occitanes-dauvergne-2024\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"los Rescontres occitanes d\u2019Auvergne 2024\" \/>\n<meta property=\"og:description\" content=\"los Rescontres occitanes d\u2019Auvergne 2024 lo CFPO Montanh\u00f2l vous convie aux Rescontres occitanes d\u2019Auvergne, del 6 al 10 juillet 2024 a Saint-Bonnet-pr\u00e8s-Riom. Venez vivre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cfpo-montanhol.org\/2024\/05\/02\/les-rencontres-occitanes-dauvergne-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-01T22:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cfpo.kiss-os.com\/wp-content\/uploads\/2025\/08\/0da50-img_1586-Grand.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1620\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"olivier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"los Rescontres occitanes d\u2019Auvergne 2024\" \/>\n<meta name=\"twitter:description\" content=\"los Rescontres occitanes d\u2019Auvergne 2024 lo CFPO Montanh\u00f2l vous convie aux Rescontres occitanes d\u2019Auvergne, del 6 al 10 juillet 2024 a Saint-Bonnet-pr\u00e8s-Riom. Venez vivre\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"olivier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cfpo-montanhol.org\/2024\/05\/02\/les-rencontres-occitanes-dauvergne-2024\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/eveniments\/los-rescontres-occitanes-dauvergne-2024\/\"},\"author\":{\"name\":\"olivier\",\"@id\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/#\/schema\/person\/32f0c924f31825018ea216afa1da90fd\"},\"headline\":\"los Rescontres occitanes d\u2019Auvergne 2024\",\"datePublished\":\"2024-05-01T22:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/eveniments\/los-rescontres-occitanes-dauvergne-2024\/\"},\"wordCount\":457,\"publisher\":{\"@id\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/cfpo-montanhol.org\/2024\/05\/02\/les-rencontres-occitanes-dauvergne-2024\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cfpo.kiss-os.com\/wp-content\/uploads\/2025\/08\/0da50-img_1586-Grand.jpg\",\"keywords\":[\"eveniment\",\"occitan\",\"rescontres occitanas\"],\"articleSection\":[\"Eveniments\",\"Rescontres occitanas\"],\"inLanguage\":\"oc-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/eveniments\/los-rescontres-occitanes-dauvergne-2024\/\",\"url\":\"https:\/\/cfpo-montanhol.org\/2024\/05\/02\/les-rencontres-occitanes-dauvergne-2024\/\",\"name\":\"los Rescontres occitanes d\u2019Auvergne 2024\",\"isPartOf\":{\"@id\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cfpo-montanhol.org\/2024\/05\/02\/les-rencontres-occitanes-dauvergne-2024\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cfpo-montanhol.org\/2024\/05\/02\/les-rencontres-occitanes-dauvergne-2024\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cfpo.kiss-os.com\/wp-content\/uploads\/2025\/08\/0da50-img_1586-Grand.jpg\",\"datePublished\":\"2024-05-01T22:00:00+00:00\",\"description\":\"los Rescontres occitanes d\u2019Auvergne 2024 lo CFPO Montanh\u00f2l vous convie aux Rescontres occitanes d\u2019Auvergne, del 6 al 10 juillet 2024 a Saint-Bonnet-pr\u00e8s-Riom. Venez vivre\",\"breadcrumb\":{\"@id\":\"https:\/\/cfpo-montanhol.org\/2024\/05\/02\/les-rencontres-occitanes-dauvergne-2024\/#breadcrumb\"},\"inLanguage\":\"oc-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cfpo-montanhol.org\/2024\/05\/02\/les-rencontres-occitanes-dauvergne-2024\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"oc-FR\",\"@id\":\"https:\/\/cfpo-montanhol.org\/2024\/05\/02\/les-rencontres-occitanes-dauvergne-2024\/#primaryimage\",\"url\":\"https:\/\/cfpo.kiss-os.com\/wp-content\/uploads\/2025\/08\/0da50-img_1586-Grand.jpg\",\"contentUrl\":\"https:\/\/cfpo.kiss-os.com\/wp-content\/uploads\/2025\/08\/0da50-img_1586-Grand.jpg\",\"width\":1620,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cfpo-montanhol.org\/2024\/05\/02\/les-rencontres-occitanes-dauvergne-2024\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"los Rescontres occitanes d\u2019Auvergne 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/#website\",\"url\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/\",\"name\":\"CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane\",\"description\":\"Transmettre la langue et la culture occitanes, pour faire vivre nos territoires.\",\"publisher\":{\"@id\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"oc-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/#organization\",\"name\":\"CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane\",\"url\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"oc-FR\",\"@id\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cfpo.kiss-os.com\/wp-content\/uploads\/2025\/07\/logo_CFPO-Montanhol_L150.png\",\"contentUrl\":\"https:\/\/cfpo.kiss-os.com\/wp-content\/uploads\/2025\/07\/logo_CFPO-Montanhol_L150.png\",\"width\":278,\"height\":150,\"caption\":\"CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane\"},\"image\":{\"@id\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/#\/schema\/person\/32f0c924f31825018ea216afa1da90fd\",\"name\":\"olivier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"oc-FR\",\"@id\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c46edfa24d0decc8df4906379b15e080b568bc243e9f7393d9ab41ae48617611?s=80&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c46edfa24d0decc8df4906379b15e080b568bc243e9f7393d9ab41ae48617611?s=80&d=mm&r=g\",\"caption\":\"olivier\"},\"sameAs\":[\"https:\/\/cfpo.kiss-os.com\"],\"url\":\"https:\/\/cfpo.kiss-os.com\/oc-fr\/author\/olivier\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"los Rescontres occitanes d\u2019Auvergne 2024","description":"los Rescontres occitanes d\u2019Auvergne 2024 lo CFPO Montanh\u00f2l vous convie aux Rescontres occitanes d\u2019Auvergne, del 6 al 10 juillet 2024 a Saint-Bonnet-pr\u00e8s-Riom. Venez vivre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cfpo-montanhol.org\/2024\/05\/02\/les-rencontres-occitanes-dauvergne-2024\/","og_locale":"en_US","og_type":"article","og_title":"los Rescontres occitanes d\u2019Auvergne 2024","og_description":"los Rescontres occitanes d\u2019Auvergne 2024 lo CFPO Montanh\u00f2l vous convie aux Rescontres occitanes d\u2019Auvergne, del 6 al 10 juillet 2024 a Saint-Bonnet-pr\u00e8s-Riom. Venez vivre","og_url":"https:\/\/cfpo-montanhol.org\/2024\/05\/02\/les-rencontres-occitanes-dauvergne-2024\/","og_site_name":"CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane","article_published_time":"2024-05-01T22:00:00+00:00","og_image":[{"width":1620,"height":1080,"url":"https:\/\/cfpo.kiss-os.com\/wp-content\/uploads\/2025\/08\/0da50-img_1586-Grand.jpg","type":"image\/jpeg"}],"author":"olivier","twitter_card":"summary_large_image","twitter_title":"los Rescontres occitanes d\u2019Auvergne 2024","twitter_description":"los Rescontres occitanes d\u2019Auvergne 2024 lo CFPO Montanh\u00f2l vous convie aux Rescontres occitanes d\u2019Auvergne, del 6 al 10 juillet 2024 a Saint-Bonnet-pr\u00e8s-Riom. Venez vivre","twitter_misc":{"Written by":"olivier","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cfpo-montanhol.org\/2024\/05\/02\/les-rencontres-occitanes-dauvergne-2024\/#article","isPartOf":{"@id":"https:\/\/cfpo.kiss-os.com\/oc-fr\/eveniments\/los-rescontres-occitanes-dauvergne-2024\/"},"author":{"name":"olivier","@id":"https:\/\/cfpo.kiss-os.com\/oc-fr\/#\/schema\/person\/32f0c924f31825018ea216afa1da90fd"},"headline":"los Rescontres occitanes d\u2019Auvergne 2024","datePublished":"2024-05-01T22:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/cfpo.kiss-os.com\/oc-fr\/eveniments\/los-rescontres-occitanes-dauvergne-2024\/"},"wordCount":457,"publisher":{"@id":"https:\/\/cfpo.kiss-os.com\/oc-fr\/#organization"},"image":{"@id":"https:\/\/cfpo-montanhol.org\/2024\/05\/02\/les-rencontres-occitanes-dauvergne-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/cfpo.kiss-os.com\/wp-content\/uploads\/2025\/08\/0da50-img_1586-Grand.jpg","keywords":["eveniment","occitan","rescontres occitanas"],"articleSection":["Eveniments","Rescontres occitanas"],"inLanguage":"oc-FR"},{"@type":"WebPage","@id":"https:\/\/cfpo.kiss-os.com\/oc-fr\/eveniments\/los-rescontres-occitanes-dauvergne-2024\/","url":"https:\/\/cfpo-montanhol.org\/2024\/05\/02\/les-rencontres-occitanes-dauvergne-2024\/","name":"los Rescontres occitanes d\u2019Auvergne 2024","isPartOf":{"@id":"https:\/\/cfpo.kiss-os.com\/oc-fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cfpo-montanhol.org\/2024\/05\/02\/les-rencontres-occitanes-dauvergne-2024\/#primaryimage"},"image":{"@id":"https:\/\/cfpo-montanhol.org\/2024\/05\/02\/les-rencontres-occitanes-dauvergne-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/cfpo.kiss-os.com\/wp-content\/uploads\/2025\/08\/0da50-img_1586-Grand.jpg","datePublished":"2024-05-01T22:00:00+00:00","description":"los Rescontres occitanes d\u2019Auvergne 2024 lo CFPO Montanh\u00f2l vous convie aux Rescontres occitanes d\u2019Auvergne, del 6 al 10 juillet 2024 a Saint-Bonnet-pr\u00e8s-Riom. Venez vivre","breadcrumb":{"@id":"https:\/\/cfpo-montanhol.org\/2024\/05\/02\/les-rencontres-occitanes-dauvergne-2024\/#breadcrumb"},"inLanguage":"oc-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cfpo-montanhol.org\/2024\/05\/02\/les-rencontres-occitanes-dauvergne-2024\/"]}]},{"@type":"ImageObject","inLanguage":"oc-FR","@id":"https:\/\/cfpo-montanhol.org\/2024\/05\/02\/les-rencontres-occitanes-dauvergne-2024\/#primaryimage","url":"https:\/\/cfpo.kiss-os.com\/wp-content\/uploads\/2025\/08\/0da50-img_1586-Grand.jpg","contentUrl":"https:\/\/cfpo.kiss-os.com\/wp-content\/uploads\/2025\/08\/0da50-img_1586-Grand.jpg","width":1620,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/cfpo-montanhol.org\/2024\/05\/02\/les-rencontres-occitanes-dauvergne-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/cfpo.kiss-os.com\/oc-fr\/"},{"@type":"ListItem","position":2,"name":"los Rescontres occitanes d\u2019Auvergne 2024"}]},{"@type":"WebSite","@id":"https:\/\/cfpo.kiss-os.com\/oc-fr\/#website","url":"https:\/\/cfpo.kiss-os.com\/oc-fr\/","name":"CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane","description":"Transmettre la langue et la culture occitanes, pour faire vivre nos territoires.","publisher":{"@id":"https:\/\/cfpo.kiss-os.com\/oc-fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cfpo.kiss-os.com\/oc-fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"oc-FR"},{"@type":"Organization","@id":"https:\/\/cfpo.kiss-os.com\/oc-fr\/#organization","name":"CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane","url":"https:\/\/cfpo.kiss-os.com\/oc-fr\/","logo":{"@type":"ImageObject","inLanguage":"oc-FR","@id":"https:\/\/cfpo.kiss-os.com\/oc-fr\/#\/schema\/logo\/image\/","url":"https:\/\/cfpo.kiss-os.com\/wp-content\/uploads\/2025\/07\/logo_CFPO-Montanhol_L150.png","contentUrl":"https:\/\/cfpo.kiss-os.com\/wp-content\/uploads\/2025\/07\/logo_CFPO-Montanhol_L150.png","width":278,"height":150,"caption":"CFPO Montanh\u00f2l \u2013 Centre de Formation Professionnelle Occitane"},"image":{"@id":"https:\/\/cfpo.kiss-os.com\/oc-fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cfpo.kiss-os.com\/oc-fr\/#\/schema\/person\/32f0c924f31825018ea216afa1da90fd","name":"olivier","image":{"@type":"ImageObject","inLanguage":"oc-FR","@id":"https:\/\/cfpo.kiss-os.com\/oc-fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c46edfa24d0decc8df4906379b15e080b568bc243e9f7393d9ab41ae48617611?s=80&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c46edfa24d0decc8df4906379b15e080b568bc243e9f7393d9ab41ae48617611?s=80&d=mm&r=g","caption":"olivier"},"sameAs":["https:\/\/cfpo.kiss-os.com"],"url":"https:\/\/cfpo.kiss-os.com\/oc-fr\/author\/olivier\/"}]}},"_links":{"self":[{"href":"https:\/\/cfpo.kiss-os.com\/oc-fr\/wp-json\/wp\/v2\/posts\/5609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cfpo.kiss-os.com\/oc-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cfpo.kiss-os.com\/oc-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cfpo.kiss-os.com\/oc-fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cfpo.kiss-os.com\/oc-fr\/wp-json\/wp\/v2\/comments?post=5609"}],"version-history":[{"count":0,"href":"https:\/\/cfpo.kiss-os.com\/oc-fr\/wp-json\/wp\/v2\/posts\/5609\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cfpo.kiss-os.com\/oc-fr\/wp-json\/wp\/v2\/media\/5435"}],"wp:attachment":[{"href":"https:\/\/cfpo.kiss-os.com\/oc-fr\/wp-json\/wp\/v2\/media?parent=5609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cfpo.kiss-os.com\/oc-fr\/wp-json\/wp\/v2\/categories?post=5609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cfpo.kiss-os.com\/oc-fr\/wp-json\/wp\/v2\/tags?post=5609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}